{"id":11815,"date":"2013-11-29T16:26:52","date_gmt":"2013-11-29T15:26:52","guid":{"rendered":"https:\/\/staging.capitalmind.com\/deals\/sale-of-mersen-industrial-mixers-engineering-business\/"},"modified":"2020-08-20T14:19:41","modified_gmt":"2020-08-20T12:19:41","slug":"verkauf-von-mersens-engineering-geschaeft-fuer-industriemischer","status":"publish","type":"deals","link":"https:\/\/www.investec.com\/advisory\/de\/deals\/verkauf-von-mersens-engineering-geschaeft-fuer-industriemischer\/","title":{"rendered":"Verkauf von Mersen&#8217;s engineering-gesch\u00e4ft f\u00fcr Industriemischer"},"content":{"rendered":"<h2>Unsere Arbeit<\/h2>\n<ul>\n<li>Beauftragt, das Unternehmen f\u00fcr den Verkauf vorzubereiten und den Ver\u00e4u\u00dferungsprozess zu leiten: von der Identifizierung potenzieller K\u00e4ufer, den Vorgespr\u00e4chen bis zur Vorbereitung und Freigabe der relevanten Verkaufsdokumentation, dem Management des Due-Diligence-Prozesses bis zur Verhandlung der rechtlichen Dokumentation<\/li>\n<li>Unsere langj\u00e4hrige Erfahrung in der Unterst\u00fctzung gro\u00dfer Unternehmen bei der Ver\u00e4u\u00dferung von Nicht-Kerngesch\u00e4ften in Verbindung mit unserem gesch\u00e4ftsorientierten M&amp;A-Ansatz und unserer &#8222;Going the extra-mile&#8220; Einstellung waren der Schl\u00fcssel f\u00fcr die ma\u00dfgeschneiderte und z\u00fcgige Durchf\u00fchrung dieser Transaktion<\/li>\n<\/ul>\n<h2>\u00dcber den Deal<\/h2>\n<p>Das in der N\u00e4he von Lyon (Frankreich) angesiedelte Unternehmen ist auf die Konstruktion und Herstellung von industriellen Mischern und Laufr\u00e4dern spezialisiert, die an internationale Kunden in Prozessindustrien wie Wasseraufbereitung, Phosphors\u00e4ure, Feinchemikalien, Pharmazeutika sowie \u00d6l und Gas verkauft werden.<\/p>\n<p>Die JFI Group ist auf hochtechnische Filtrations-, Trenn- und Dosieranlagen und -l\u00f6sungen f\u00fcr die Bergbau-, Chemie- und Prozessindustrie spezialisiert. Die JFI Group wird von einem franz\u00f6sischen Unternehmer, Michel Jamey, kontrolliert, der von der Private-Equity-Firma Naxicap unterst\u00fctzt wird.<\/p>\n<p>Es wird erwartet, dass die \u00dcbernahme starke Synergien mit den bestehenden Aktivit\u00e4ten der JFI Group erzeugen wird.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unsere Arbeit Beauftragt, das Unternehmen f\u00fcr den Verkauf vorzubereiten und den Ver\u00e4u\u00dferungsprozess zu leiten: von der Identifizierung potenzieller K\u00e4ufer, den&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","dt":[],"sector":[3709],"dealtype":[3722,3708],"clienttype":[3702],"class_list":["post-11815","deals","type-deals","status-publish","hentry","sector-industrials-de","dealtype-carve-out-de","dealtype-sell-side-de","clienttype-familienunternehmen-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verkauf von Mersen&#039;s engineering-gesch\u00e4ft f\u00fcr Industriemischer | Investec Business Advisory<\/title>\n<meta name=\"description\" content=\"Investec unterst\u00fctzte Mersen, Elektrospezialit\u00e4ten und Materialien auf Graphitbasis, beim Verkauf seines Gesch\u00e4ftsbereichs Industriemischerbau an die JFI-Gruppe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.investec.com\/advisory\/de\/deals\/verkauf-von-mersens-engineering-geschaeft-fuer-industriemischer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verkauf von Mersen&#039;s engineering-gesch\u00e4ft f\u00fcr Industriemischer | Investec Business Advisory\" \/>\n<meta property=\"og:description\" content=\"Investec unterst\u00fctzte Mersen, Elektrospezialit\u00e4ten und Materialien auf Graphitbasis, beim Verkauf seines Gesch\u00e4ftsbereichs Industriemischerbau an die JFI-Gruppe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.investec.com\/advisory\/de\/deals\/verkauf-von-mersens-engineering-geschaeft-fuer-industriemischer\/\" \/>\n<meta property=\"og:site_name\" content=\"Investec Business Advisory\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-20T12:19:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/deals\\\/verkauf-von-mersens-engineering-geschaeft-fuer-industriemischer\\\/\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/deals\\\/verkauf-von-mersens-engineering-geschaeft-fuer-industriemischer\\\/\",\"name\":\"Verkauf von Mersen's engineering-gesch\u00e4ft f\u00fcr Industriemischer | Investec Business Advisory\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/#website\"},\"datePublished\":\"2013-11-29T15:26:52+00:00\",\"dateModified\":\"2020-08-20T12:19:41+00:00\",\"description\":\"Investec unterst\u00fctzte Mersen, Elektrospezialit\u00e4ten und Materialien auf Graphitbasis, beim Verkauf seines Gesch\u00e4ftsbereichs Industriemischerbau an die JFI-Gruppe.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/deals\\\/verkauf-von-mersens-engineering-geschaeft-fuer-industriemischer\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/deals\\\/verkauf-von-mersens-engineering-geschaeft-fuer-industriemischer\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/deals\\\/verkauf-von-mersens-engineering-geschaeft-fuer-industriemischer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verkauf von Mersen&#8217;s engineering-gesch\u00e4ft f\u00fcr Industriemischer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/\",\"name\":\"Investec Business Advisory\",\"description\":\"Investec Business Advisory\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/#organization\",\"name\":\"Capitalmind Investec\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Logo_Investec_cmjn_6.jpg\",\"contentUrl\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Logo_Investec_cmjn_6.jpg\",\"width\":1120,\"height\":1121,\"caption\":\"Capitalmind Investec\"},\"image\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/capitalmind---corporate-finance-advisory\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC4bVt7iNejh8tGT6Qfa9R4w\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verkauf von Mersen's engineering-gesch\u00e4ft f\u00fcr Industriemischer | Investec Business Advisory","description":"Investec unterst\u00fctzte Mersen, Elektrospezialit\u00e4ten und Materialien auf Graphitbasis, beim Verkauf seines Gesch\u00e4ftsbereichs Industriemischerbau an die JFI-Gruppe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.investec.com\/advisory\/de\/deals\/verkauf-von-mersens-engineering-geschaeft-fuer-industriemischer\/","og_locale":"de_DE","og_type":"article","og_title":"Verkauf von Mersen's engineering-gesch\u00e4ft f\u00fcr Industriemischer | Investec Business Advisory","og_description":"Investec unterst\u00fctzte Mersen, Elektrospezialit\u00e4ten und Materialien auf Graphitbasis, beim Verkauf seines Gesch\u00e4ftsbereichs Industriemischerbau an die JFI-Gruppe.","og_url":"https:\/\/www.investec.com\/advisory\/de\/deals\/verkauf-von-mersens-engineering-geschaeft-fuer-industriemischer\/","og_site_name":"Investec Business Advisory","article_modified_time":"2020-08-20T12:19:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.investec.com\/advisory\/de\/deals\/verkauf-von-mersens-engineering-geschaeft-fuer-industriemischer\/","url":"https:\/\/www.investec.com\/advisory\/de\/deals\/verkauf-von-mersens-engineering-geschaeft-fuer-industriemischer\/","name":"Verkauf von Mersen's engineering-gesch\u00e4ft f\u00fcr Industriemischer | Investec Business Advisory","isPartOf":{"@id":"https:\/\/www.investec.com\/advisory\/de\/#website"},"datePublished":"2013-11-29T15:26:52+00:00","dateModified":"2020-08-20T12:19:41+00:00","description":"Investec unterst\u00fctzte Mersen, Elektrospezialit\u00e4ten und Materialien auf Graphitbasis, beim Verkauf seines Gesch\u00e4ftsbereichs Industriemischerbau an die JFI-Gruppe.","breadcrumb":{"@id":"https:\/\/www.investec.com\/advisory\/de\/deals\/verkauf-von-mersens-engineering-geschaeft-fuer-industriemischer\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.investec.com\/advisory\/de\/deals\/verkauf-von-mersens-engineering-geschaeft-fuer-industriemischer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.investec.com\/advisory\/de\/deals\/verkauf-von-mersens-engineering-geschaeft-fuer-industriemischer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.investec.com\/advisory\/de\/"},{"@type":"ListItem","position":2,"name":"Verkauf von Mersen&#8217;s engineering-gesch\u00e4ft f\u00fcr Industriemischer"}]},{"@type":"WebSite","@id":"https:\/\/www.investec.com\/advisory\/de\/#website","url":"https:\/\/www.investec.com\/advisory\/de\/","name":"Investec Business Advisory","description":"Investec Business Advisory","publisher":{"@id":"https:\/\/www.investec.com\/advisory\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.investec.com\/advisory\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.investec.com\/advisory\/de\/#organization","name":"Capitalmind Investec","url":"https:\/\/www.investec.com\/advisory\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.investec.com\/advisory\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.investec.com\/advisory\/wp-content\/uploads\/2020\/01\/Logo_Investec_cmjn_6.jpg","contentUrl":"https:\/\/www.investec.com\/advisory\/wp-content\/uploads\/2020\/01\/Logo_Investec_cmjn_6.jpg","width":1120,"height":1121,"caption":"Capitalmind Investec"},"image":{"@id":"https:\/\/www.investec.com\/advisory\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/capitalmind---corporate-finance-advisory","https:\/\/www.youtube.com\/channel\/UC4bVt7iNejh8tGT6Qfa9R4w"]}]}},"_links":{"self":[{"href":"https:\/\/www.investec.com\/advisory\/de\/wp-json\/wp\/v2\/deals\/11815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.investec.com\/advisory\/de\/wp-json\/wp\/v2\/deals"}],"about":[{"href":"https:\/\/www.investec.com\/advisory\/de\/wp-json\/wp\/v2\/types\/deals"}],"wp:attachment":[{"href":"https:\/\/www.investec.com\/advisory\/de\/wp-json\/wp\/v2\/media?parent=11815"}],"wp:term":[{"taxonomy":"dt","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/de\/wp-json\/wp\/v2\/dt?post=11815"},{"taxonomy":"sector","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/de\/wp-json\/wp\/v2\/sector?post=11815"},{"taxonomy":"dealtype","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/de\/wp-json\/wp\/v2\/dealtype?post=11815"},{"taxonomy":"clienttype","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/de\/wp-json\/wp\/v2\/clienttype?post=11815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}