{"id":58621,"date":"2026-06-23T18:10:11","date_gmt":"2026-06-23T16:10:11","guid":{"rendered":"https:\/\/editing.capitalmind.com\/?post_type=deals&#038;p=58621"},"modified":"2026-07-20T09:34:11","modified_gmt":"2026-07-20T07:34:11","slug":"lbo-von-lauralu-mit-unterstuetzung-von-eurazeo-infrastructure-partners","status":"publish","type":"deals","link":"https:\/\/www.investec.com\/advisory\/de\/deals\/lbo-von-lauralu-mit-unterstuetzung-von-eurazeo-infrastructure-partners\/","title":{"rendered":"LBO von Lauralu mit Unterst\u00fctzung von Eurazeo Infrastructure Partners"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Investec hat die Gesellschafter von Lauralu bei dem von Eurazeo Infrastructure Partners finanzierten Sekund\u00e4r-LBO beraten<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00dcber den Deal<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Lauralu wurde 1998 in Saverdun (Frankreich) gegr\u00fcndet und verf\u00fcgt \u00fcber eine etablierte Pr\u00e4senz im Vereinigten K\u00f6nigreich, in Deutschland, den nordischen L\u00e4ndern und Spanien. Das Unternehmen entwirft, fertigt, installiert und passt gro\u00dffl\u00e4chige, demontierbare Konstruktionen f\u00fcr industrielle Lagerhaltung, Logistikplattformen und Betriebsanlagen an. Gest\u00fctzt auf einen umfangreichen, gut investierten und wiederverwendbaren Anlagenbestand liefert Lauralu integrierte Infrastrukturl\u00f6sungen schnell und in gro\u00dfem Ma\u00dfstab, um den kritischen Anforderungen seiner namhaften Industriekunden gerecht zu werden. Der \u00fcberwiegende Teil der operativen Leistung von Lauralu wird im Rahmen mehrj\u00e4hriger Mietvertr\u00e4ge erbracht, die durch eine hohe Verl\u00e4ngerungsquote gest\u00fctzt werden \u2013 ein Zeichen f\u00fcr die gesch\u00e4ftskritische Bedeutung der von Lauralu bereitgestellten Infrastruktur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seit 2014 unter der Leitung von CEO Olivier Hohn, der das Unternehmen auch \u00fcbernommen hat, und seit 2018 mit Unterst\u00fctzung von Evolem hat Lauralu eine starke Erfolgsbilanz nachhaltigen Wachstums durch organische Expansion und gezielte Akquisitionen aufgebaut: Der Umsatz stieg von 4 Mio. \u20ac im Jahr 2014 auf ca. 80 Mio. \u20ac im Jahr 2025, und das Unternehmen verwaltet mittlerweile \u00fcber 400.000 m\u00b2 an eingesetzter Infrastruktur in ganz Europa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Anschluss an ein von Investec-Teams geleitetes Auktionsverfahren hat Eurazeo Infrastructure Partners eine Mehrheitsbeteiligung an der Lauralu-Gruppe erworben, unterst\u00fctzt von lokalen Investoren aus dem \u00d6kosystem, darunter Origine Partners, Croissance Sud, Sofilaro und IRDI.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eurazeo wird das Wachstum von Lauralu durch eine proaktive Verm\u00f6gensverwaltungsstrategie unterst\u00fctzen, deren Schwerpunkt auf der St\u00e4rkung des Mietmodells, der Optimierung der Organisation und der Verfolgung selektiver M&amp;A-Ma\u00dfnahmen in einem stark fragmentierten Markt liegt. Durch diese Investition treibt Eurazeo zudem seine Nachhaltigkeitsziele voran, indem es ein zirkul\u00e4res Verm\u00f6gensmodell unterst\u00fctzt, das durch hohe Wiederverwendungsraten, versetzbare Strukturen und einen geringen CO\u2082-Fu\u00dfabdruck gekennzeichnet ist und vollst\u00e4ndig im Einklang mit der EU-Taxonomie steht.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Unsere Arbeit<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Investec fungierte w\u00e4hrend des gesamten Verkaufsprozesses als exklusiver Finanzberater der Aktion\u00e4re von Lauralu:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Vorbereitung der Transaktion<\/strong>: Wir bereiteten das Unternehmen auf den Verkauf vor, indem wir<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>die \u201eEquity Story\u201c definierten,<\/li>\n\n\n\n<li>den Gesch\u00e4ftsplan der Gesch\u00e4ftsf\u00fchrung pr\u00fcften,<\/li>\n\n\n\n<li>die Due-Diligence-Pr\u00fcfung des Verk\u00e4ufers begleiteten<\/li>\n\n\n\n<li>und die entsprechenden Marketingunterlagen erstellten.<\/li>\n\n\n\n<li>Zudem legten wir die Transaktionsstrategie (Ablauf und Tempo des Prozesses) auf der Grundlage des Feedbacks fest, das wir im Vorfeld aus Gespr\u00e4chen mit einer Auswahl potenzieller K\u00e4ufer erhalten hatten.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Abwicklung der Transaktion<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Wir haben einen Auktionsprozess mit einer begrenzten Anzahl qualifizierter Bieter durchgef\u00fchrt,<\/li>\n\n\n\n<li>das Managementteam bei Gespr\u00e4chen mit potenziellen Bietern unterst\u00fctzt,<\/li>\n\n\n\n<li>die Due-Diligence-Phase der Bieter \u00fcberwacht und<\/li>\n\n\n\n<li>bei den abschlie\u00dfenden Verhandlungen \u00fcber die Transaktionsunterlagen mitgewirkt, um die g\u00fcnstigsten Transaktionsbedingungen zu sichern.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Diese Transaktion verdeutlicht unsere F\u00e4higkeit, Private-Equity-Fonds und Family Offices beim Verkauf schnell wachsender paneurop\u00e4ischer Plattformen zu unterst\u00fctzen, und st\u00e4rkt unsere Expertise im Bereich des professionellen Vermietungsmarktes weiter.<\/strong><\/p>\n\n\n<section class=\"content--block quoteBlock \">\n    <div class=\"holder\">\n        <div class=\"stories slide-up d-flex\" data-scroll=\"\">\n                            <div class=\"stories__bg\">\n                    <img decoding=\"async\" src=\"https:\/\/www.investec.com\/advisory\/wp-content\/uploads\/2026\/07\/Olivier-Hohn-v3.png\"\n                        alt=\"\" \/>\n                <\/div>\n            \n            <blockquote class=\"stories__desc\" >\n                <span class=\"stories__desc_quote\">\u201c\u201d<\/span>\n\n                                    <div class=\"justified\"><p>Ich m\u00f6chte mich ganz herzlich beim Investec-Team bedanken, mit dem ich sehr gerne zusammengearbeitet habe. Das Team war praxisorientiert, reaktionsschnell und stets professionell und hat zudem einen echten Teamgeist vermittelt, der den entscheidenden Unterschied ausgemacht hat. Diese Kombination war entscheidend daf\u00fcr, dass mein Team w\u00e4hrend dieses wirklich anspruchsvollen Prozesses motiviert und voller Tatendrang blieb. Vielen Dank an das gesamte Team.<\/p>\n<\/div>                \n\n                                    <cite>&#8211; Olivier Hohn, CEO, Lauralu<\/cite>\n                            <\/blockquote>\n        <\/div><!-- \/.stories -->\n    <\/div>\n<\/section>\n<!-- ============= End of \/.QuoteBlock =============== -->\n\n<section class=\"content--block quoteBlock \">\n    <div class=\"holder\">\n        <div class=\"stories slide-up d-flex\" data-scroll=\"\">\n                            <div class=\"stories__bg\">\n                    <img decoding=\"async\" src=\"https:\/\/www.investec.com\/advisory\/wp-content\/uploads\/2026\/06\/victor-d-herouville-round.png\"\n                        alt=\"\" \/>\n                <\/div>\n            \n            <blockquote class=\"stories__desc\" >\n                <span class=\"stories__desc_quote\">\u201c\u201d<\/span>\n\n                                    <div class=\"justified\"><p>Die Unterst\u00fctzung durch Investec w\u00e4hrend des gesamten Verkaufsprozesses von Lauralu trug entscheidend zum Erfolg der Transaktion bei. Das Team verband ein hohes Ma\u00df an Engagement mit au\u00dfergew\u00f6hnlicher Reaktionsf\u00e4higkeit \u2013 beides war unerl\u00e4sslich, um das Tempo des Prozesses aufrechtzuerhalten. Neben ihrer taktischen Kompetenz bei der F\u00fchrung der Verhandlungen war es auch ihre F\u00e4higkeit, einen Schritt zur\u00fcckzutreten, eine strategische Perspektive einzubringen und alle Beteiligten mit ins Boot zu holen, die das Projekt zum Erfolg f\u00fchrte. Ein vertrauensw\u00fcrdiger Partner, der durchweg Pr\u00e4zision, Pragmatismus und fundiertes Urteilsverm\u00f6gen an den Tag legte.<\/p>\n<\/div>                \n\n                                    <cite>&#8211; Victor d&#039;H\u00e9rouville, Director, Evolem<\/cite>\n                            <\/blockquote>\n        <\/div><!-- \/.stories -->\n    <\/div>\n<\/section>\n<!-- ============= End of \/.QuoteBlock =============== -->","protected":false},"excerpt":{"rendered":"<p>Investec hat die Gesellschafter von Lauralu bei dem von Eurazeo Infrastructure Partners finanzierten Sekund\u00e4r-LBO beraten \u00dcber den Deal Lauralu wurde&#8230;<\/p>\n","protected":false},"featured_media":58594,"template":"","dt":[],"sector":[3707,16927],"dealtype":[3713,3712,3708],"clienttype":[3727,3714],"class_list":["post-58621","deals","type-deals","status-publish","has-post-thumbnail","hentry","sector-business-services-de","sector-energie-und-infrastruktur","dealtype-mbo-de","dealtype-debt-advisory-de","dealtype-sell-side-de","clienttype-founders-entrepreneurs-de","clienttype-financial-investors-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LBO von Lauralu mit Unterst\u00fctzung von Eurazeo Infrastructure Partners | Investec Business Advisory<\/title>\n<meta name=\"description\" content=\"Investec hat die Gesellschafter von Lauralu bei dem von Eurazeo Infrastructure Partners finanzierten Sekund\u00e4r-LBO beraten\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.investec.com\/advisory\/de\/deals\/lbo-von-lauralu-mit-unterstuetzung-von-eurazeo-infrastructure-partners\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LBO von Lauralu mit Unterst\u00fctzung von Eurazeo Infrastructure Partners | Investec Business Advisory\" \/>\n<meta property=\"og:description\" content=\"Investec hat die Gesellschafter von Lauralu bei dem von Eurazeo Infrastructure Partners finanzierten Sekund\u00e4r-LBO beraten\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.investec.com\/advisory\/de\/deals\/lbo-von-lauralu-mit-unterstuetzung-von-eurazeo-infrastructure-partners\/\" \/>\n<meta property=\"og:site_name\" content=\"Investec Business Advisory\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-20T07:34:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.investec.com\/advisory\/wp-content\/uploads\/2026\/06\/Megastructure-UK-V3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1456\" \/>\n\t<meta property=\"og:image:height\" content=\"743\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/deals\\\/lbo-von-lauralu-mit-unterstuetzung-von-eurazeo-infrastructure-partners\\\/\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/deals\\\/lbo-von-lauralu-mit-unterstuetzung-von-eurazeo-infrastructure-partners\\\/\",\"name\":\"LBO von Lauralu mit Unterst\u00fctzung von Eurazeo Infrastructure Partners | Investec Business Advisory\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/deals\\\/lbo-von-lauralu-mit-unterstuetzung-von-eurazeo-infrastructure-partners\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/deals\\\/lbo-von-lauralu-mit-unterstuetzung-von-eurazeo-infrastructure-partners\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Megastructure-UK-V3.jpg\",\"datePublished\":\"2026-06-23T16:10:11+00:00\",\"dateModified\":\"2026-07-20T07:34:11+00:00\",\"description\":\"Investec hat die Gesellschafter von Lauralu bei dem von Eurazeo Infrastructure Partners finanzierten Sekund\u00e4r-LBO beraten\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/deals\\\/lbo-von-lauralu-mit-unterstuetzung-von-eurazeo-infrastructure-partners\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/deals\\\/lbo-von-lauralu-mit-unterstuetzung-von-eurazeo-infrastructure-partners\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/deals\\\/lbo-von-lauralu-mit-unterstuetzung-von-eurazeo-infrastructure-partners\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Megastructure-UK-V3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Megastructure-UK-V3.jpg\",\"width\":1456,\"height\":743},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/deals\\\/lbo-von-lauralu-mit-unterstuetzung-von-eurazeo-infrastructure-partners\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LBO von Lauralu mit Unterst\u00fctzung von Eurazeo Infrastructure Partners\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/\",\"name\":\"Investec Business Advisory\",\"description\":\"Investec Business Advisory\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/#organization\",\"name\":\"Capitalmind Investec\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Logo_Investec_cmjn_6.jpg\",\"contentUrl\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Logo_Investec_cmjn_6.jpg\",\"width\":1120,\"height\":1121,\"caption\":\"Capitalmind Investec\"},\"image\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/capitalmind---corporate-finance-advisory\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC4bVt7iNejh8tGT6Qfa9R4w\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LBO von Lauralu mit Unterst\u00fctzung von Eurazeo Infrastructure Partners | Investec Business Advisory","description":"Investec hat die Gesellschafter von Lauralu bei dem von Eurazeo Infrastructure Partners finanzierten Sekund\u00e4r-LBO beraten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.investec.com\/advisory\/de\/deals\/lbo-von-lauralu-mit-unterstuetzung-von-eurazeo-infrastructure-partners\/","og_locale":"de_DE","og_type":"article","og_title":"LBO von Lauralu mit Unterst\u00fctzung von Eurazeo Infrastructure Partners | Investec Business Advisory","og_description":"Investec hat die Gesellschafter von Lauralu bei dem von Eurazeo Infrastructure Partners finanzierten Sekund\u00e4r-LBO beraten","og_url":"https:\/\/www.investec.com\/advisory\/de\/deals\/lbo-von-lauralu-mit-unterstuetzung-von-eurazeo-infrastructure-partners\/","og_site_name":"Investec Business Advisory","article_modified_time":"2026-07-20T07:34:11+00:00","og_image":[{"width":1456,"height":743,"url":"https:\/\/www.investec.com\/advisory\/wp-content\/uploads\/2026\/06\/Megastructure-UK-V3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.investec.com\/advisory\/de\/deals\/lbo-von-lauralu-mit-unterstuetzung-von-eurazeo-infrastructure-partners\/","url":"https:\/\/www.investec.com\/advisory\/de\/deals\/lbo-von-lauralu-mit-unterstuetzung-von-eurazeo-infrastructure-partners\/","name":"LBO von Lauralu mit Unterst\u00fctzung von Eurazeo Infrastructure Partners | Investec Business Advisory","isPartOf":{"@id":"https:\/\/www.investec.com\/advisory\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.investec.com\/advisory\/de\/deals\/lbo-von-lauralu-mit-unterstuetzung-von-eurazeo-infrastructure-partners\/#primaryimage"},"image":{"@id":"https:\/\/www.investec.com\/advisory\/de\/deals\/lbo-von-lauralu-mit-unterstuetzung-von-eurazeo-infrastructure-partners\/#primaryimage"},"thumbnailUrl":"https:\/\/www.investec.com\/advisory\/wp-content\/uploads\/2026\/06\/Megastructure-UK-V3.jpg","datePublished":"2026-06-23T16:10:11+00:00","dateModified":"2026-07-20T07:34:11+00:00","description":"Investec hat die Gesellschafter von Lauralu bei dem von Eurazeo Infrastructure Partners finanzierten Sekund\u00e4r-LBO beraten","breadcrumb":{"@id":"https:\/\/www.investec.com\/advisory\/de\/deals\/lbo-von-lauralu-mit-unterstuetzung-von-eurazeo-infrastructure-partners\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.investec.com\/advisory\/de\/deals\/lbo-von-lauralu-mit-unterstuetzung-von-eurazeo-infrastructure-partners\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.investec.com\/advisory\/de\/deals\/lbo-von-lauralu-mit-unterstuetzung-von-eurazeo-infrastructure-partners\/#primaryimage","url":"https:\/\/www.investec.com\/advisory\/wp-content\/uploads\/2026\/06\/Megastructure-UK-V3.jpg","contentUrl":"https:\/\/www.investec.com\/advisory\/wp-content\/uploads\/2026\/06\/Megastructure-UK-V3.jpg","width":1456,"height":743},{"@type":"BreadcrumbList","@id":"https:\/\/www.investec.com\/advisory\/de\/deals\/lbo-von-lauralu-mit-unterstuetzung-von-eurazeo-infrastructure-partners\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.investec.com\/advisory\/de\/"},{"@type":"ListItem","position":2,"name":"LBO von Lauralu mit Unterst\u00fctzung von Eurazeo Infrastructure Partners"}]},{"@type":"WebSite","@id":"https:\/\/www.investec.com\/advisory\/de\/#website","url":"https:\/\/www.investec.com\/advisory\/de\/","name":"Investec Business Advisory","description":"Investec Business Advisory","publisher":{"@id":"https:\/\/www.investec.com\/advisory\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.investec.com\/advisory\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.investec.com\/advisory\/de\/#organization","name":"Capitalmind Investec","url":"https:\/\/www.investec.com\/advisory\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.investec.com\/advisory\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.investec.com\/advisory\/wp-content\/uploads\/2020\/01\/Logo_Investec_cmjn_6.jpg","contentUrl":"https:\/\/www.investec.com\/advisory\/wp-content\/uploads\/2020\/01\/Logo_Investec_cmjn_6.jpg","width":1120,"height":1121,"caption":"Capitalmind Investec"},"image":{"@id":"https:\/\/www.investec.com\/advisory\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/capitalmind---corporate-finance-advisory","https:\/\/www.youtube.com\/channel\/UC4bVt7iNejh8tGT6Qfa9R4w"]}]}},"_links":{"self":[{"href":"https:\/\/www.investec.com\/advisory\/de\/wp-json\/wp\/v2\/deals\/58621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.investec.com\/advisory\/de\/wp-json\/wp\/v2\/deals"}],"about":[{"href":"https:\/\/www.investec.com\/advisory\/de\/wp-json\/wp\/v2\/types\/deals"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/de\/wp-json\/wp\/v2\/media\/58594"}],"wp:attachment":[{"href":"https:\/\/www.investec.com\/advisory\/de\/wp-json\/wp\/v2\/media?parent=58621"}],"wp:term":[{"taxonomy":"dt","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/de\/wp-json\/wp\/v2\/dt?post=58621"},{"taxonomy":"sector","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/de\/wp-json\/wp\/v2\/sector?post=58621"},{"taxonomy":"dealtype","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/de\/wp-json\/wp\/v2\/dealtype?post=58621"},{"taxonomy":"clienttype","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/de\/wp-json\/wp\/v2\/clienttype?post=58621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}