{"id":15021,"date":"2019-09-12T15:22:44","date_gmt":"2019-09-12T13:22:44","guid":{"rendered":"https:\/\/staging.capitalmind.com\/deals\/sale-of-icar-datafirst-group-to-providence-strategic-growth\/"},"modified":"2023-06-05T17:12:33","modified_gmt":"2023-06-05T15:12:33","slug":"cession-icar-datafirst","status":"publish","type":"deals","link":"https:\/\/www.investec.com\/advisory\/fr\/deals\/cession-icar-datafirst\/","title":{"rendered":"Cession du groupe I\u2019Car Datafirst \u00e0 Providence Strategic Growth"},"content":{"rendered":"<h2>Contexte de l&rsquo;op\u00e9ration<\/h2>\n<p><strong>I\u2019Car Systems &#8211; Datafirst<\/strong> est le leader fran\u00e7ais des solutions logicielles pour la distribution automobile (Dealers Management Systems, CRM, Business Intelligence et web solutions). Le groupe cible en priorit\u00e9 les majors de la distribution automobile, les concessionnaires et les constructeurs en Europe. Avec le soutien d\u2019Argos Wityu, I\u2019Car Systems et Datafirst se sont rapproch\u00e9es en 2018 avec l&rsquo;ambition de devenir le leader d&rsquo;un march\u00e9 europ\u00e9en fragment\u00e9.<\/p>\n<p><strong>Argos Wityu<\/strong> est un groupe de capital-investissement ind\u00e9pendant implant\u00e9 \u00e0 Bruxelles, Francfort, Gen\u00e8ve, Luxembourg, Milan et Paris. Depuis sa cr\u00e9ation en 1989, le groupe a r\u00e9alis\u00e9 plus de 75 investissements dans des entreprises de taille moyenne (25 \u00e0 200 M\u20ac de valeur d\u2019entreprise). Fort d\u2019un milliard d\u2019euros sous gestion, le groupe d\u00e9veloppe une strat\u00e9gie d\u2019investissement originale qui privil\u00e9gie la transformation et la croissance des entreprises \u00e0 l\u2019effet de levier.<\/p>\n<p><strong>Providence Strategic Growth<\/strong> (PSG) est une soci\u00e9t\u00e9 du groupe Providence Equity Partners. PSG investit dans des entreprises de croissance sp\u00e9cialis\u00e9es dans l\u2019\u00e9dition de logiciels ou les services technologiques. Avec plus de 40 md$ Providence Equity est un gestionnaire d\u2019actifs de premier plan \u00e0 l\u2019\u00e9chelle mondiale. Depuis sa cr\u00e9ation en 1989, Providence Equity a investi dans plus de 180 soci\u00e9t\u00e9s et est l&rsquo;un des premiers acteurs du Private Equity \u00e0 avoir d\u00e9velopp\u00e9 une approche sectorielle syst\u00e9matique, se concentrant sur les secteurs des m\u00e9dias, des communications, de l\u2019\u00e9ducation et de l\u2019information.<\/p>\n<h2>Notre r\u00f4le<\/h2>\n<p>Investec a conseill\u00e9 <a href=\"https:\/\/argos.wityu.fund\/fr\/\" target=\"_blank\" rel=\"noopener\">Argos Wityu<\/a> tout au long du processus de cession : construction de la tactique du deal, presounding d&rsquo;acqu\u00e9reurs strat\u00e9giques et financiers, pr\u00e9paration des supports marketing, coordination des intervenants (VDD, auditeurs, avocats&#8230;), organisation d\u2019un process comp\u00e9titif avec les acqu\u00e9reurs pressentis, assistance \u00e0 la n\u00e9gociation, valorisation etc.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contexte de l&rsquo;op\u00e9ration I\u2019Car Systems &#8211; Datafirst est le leader fran\u00e7ais des solutions logicielles pour la distribution automobile (Dealers Management&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","dt":[],"sector":[3697],"dealtype":[3706,3740],"clienttype":[3720],"class_list":["post-15021","deals","type-deals","status-publish","hentry","sector-fr-sector-expertise-tmt","dealtype-cession-fr","dealtype-capital-dev-fr","clienttype-pe-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cession du groupe I\u2019Car Datafirst \u00e0 Providence Strategic Growth<\/title>\n<meta name=\"description\" content=\"Investec conseille Argos Wityu pour la cession du groupe I&#039;Car Datafirst, leader des solutions logicielles pour la distribution automobile\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.investec.com\/advisory\/fr\/deals\/cession-icar-datafirst\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cession du groupe I\u2019Car Datafirst \u00e0 Providence Strategic Growth\" \/>\n<meta property=\"og:description\" content=\"Investec conseille Argos Wityu pour la cession du groupe I&#039;Car Datafirst, leader des solutions logicielles pour la distribution automobile\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.investec.com\/advisory\/fr\/deals\/cession-icar-datafirst\/\" \/>\n<meta property=\"og:site_name\" content=\"Investec Business Advisory\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-05T15:12:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/cession-icar-datafirst\\\/\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/cession-icar-datafirst\\\/\",\"name\":\"Cession du groupe I\u2019Car Datafirst \u00e0 Providence Strategic Growth\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#website\"},\"datePublished\":\"2019-09-12T13:22:44+00:00\",\"dateModified\":\"2023-06-05T15:12:33+00:00\",\"description\":\"Investec conseille Argos Wityu pour la cession du groupe I'Car Datafirst, leader des solutions logicielles pour la distribution automobile\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/cession-icar-datafirst\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/cession-icar-datafirst\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/cession-icar-datafirst\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cession du groupe I\u2019Car Datafirst \u00e0 Providence Strategic Growth\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/\",\"name\":\"Investec Business Advisory\",\"description\":\"Investec Business Advisory\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#organization\",\"name\":\"Capitalmind Investec\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Logo_Investec_cmjn_6.jpg\",\"contentUrl\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Logo_Investec_cmjn_6.jpg\",\"width\":1120,\"height\":1121,\"caption\":\"Capitalmind Investec\"},\"image\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/capitalmind---corporate-finance-advisory\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC4bVt7iNejh8tGT6Qfa9R4w\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cession du groupe I\u2019Car Datafirst \u00e0 Providence Strategic Growth","description":"Investec conseille Argos Wityu pour la cession du groupe I'Car Datafirst, leader des solutions logicielles pour la distribution automobile","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.investec.com\/advisory\/fr\/deals\/cession-icar-datafirst\/","og_locale":"fr_FR","og_type":"article","og_title":"Cession du groupe I\u2019Car Datafirst \u00e0 Providence Strategic Growth","og_description":"Investec conseille Argos Wityu pour la cession du groupe I'Car Datafirst, leader des solutions logicielles pour la distribution automobile","og_url":"https:\/\/www.investec.com\/advisory\/fr\/deals\/cession-icar-datafirst\/","og_site_name":"Investec Business Advisory","article_modified_time":"2023-06-05T15:12:33+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.investec.com\/advisory\/fr\/deals\/cession-icar-datafirst\/","url":"https:\/\/www.investec.com\/advisory\/fr\/deals\/cession-icar-datafirst\/","name":"Cession du groupe I\u2019Car Datafirst \u00e0 Providence Strategic Growth","isPartOf":{"@id":"https:\/\/www.investec.com\/advisory\/fr\/#website"},"datePublished":"2019-09-12T13:22:44+00:00","dateModified":"2023-06-05T15:12:33+00:00","description":"Investec conseille Argos Wityu pour la cession du groupe I'Car Datafirst, leader des solutions logicielles pour la distribution automobile","breadcrumb":{"@id":"https:\/\/www.investec.com\/advisory\/fr\/deals\/cession-icar-datafirst\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.investec.com\/advisory\/fr\/deals\/cession-icar-datafirst\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.investec.com\/advisory\/fr\/deals\/cession-icar-datafirst\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.investec.com\/advisory\/fr\/"},{"@type":"ListItem","position":2,"name":"Cession du groupe I\u2019Car Datafirst \u00e0 Providence Strategic Growth"}]},{"@type":"WebSite","@id":"https:\/\/www.investec.com\/advisory\/fr\/#website","url":"https:\/\/www.investec.com\/advisory\/fr\/","name":"Investec Business Advisory","description":"Investec Business Advisory","publisher":{"@id":"https:\/\/www.investec.com\/advisory\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.investec.com\/advisory\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.investec.com\/advisory\/fr\/#organization","name":"Capitalmind Investec","url":"https:\/\/www.investec.com\/advisory\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.investec.com\/advisory\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.investec.com\/advisory\/wp-content\/uploads\/2020\/01\/Logo_Investec_cmjn_6.jpg","contentUrl":"https:\/\/www.investec.com\/advisory\/wp-content\/uploads\/2020\/01\/Logo_Investec_cmjn_6.jpg","width":1120,"height":1121,"caption":"Capitalmind Investec"},"image":{"@id":"https:\/\/www.investec.com\/advisory\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/capitalmind---corporate-finance-advisory","https:\/\/www.youtube.com\/channel\/UC4bVt7iNejh8tGT6Qfa9R4w"]}]}},"_links":{"self":[{"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/deals\/15021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/deals"}],"about":[{"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/types\/deals"}],"wp:attachment":[{"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/media?parent=15021"}],"wp:term":[{"taxonomy":"dt","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/dt?post=15021"},{"taxonomy":"sector","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/sector?post=15021"},{"taxonomy":"dealtype","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/dealtype?post=15021"},{"taxonomy":"clienttype","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/clienttype?post=15021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}