{"id":26156,"date":"2021-08-06T08:57:43","date_gmt":"2021-08-06T06:57:43","guid":{"rendered":"https:\/\/staging.capitalmind.com\/deals\/cession-di-solutions-health-a-trill-impact\/"},"modified":"2021-10-21T15:31:35","modified_gmt":"2021-10-21T13:31:35","slug":"cession-di-solutions-health-a-trill-impact","status":"publish","type":"deals","link":"https:\/\/www.investec.com\/advisory\/fr\/deals\/cession-di-solutions-health-a-trill-impact\/","title":{"rendered":"Cession d&rsquo;i-Solutions Health \u00e0 Trill Impact"},"content":{"rendered":"<h2>Contexte de l&rsquo;op\u00e9ration<\/h2>\n<p>i-SOLUTIONS Health est une soci\u00e9t\u00e9 allemande sp\u00e9cialis\u00e9e dans les logiciels pour la sant\u00e9 \u00e0 destination des h\u00f4pitaux, des laboratoires et des centres de radiologie.<\/p>\n<p>En rejoignant Trill Impact, i-SOLUTIONS int\u00e8grera le groupe Meona, un fournisseur leader sur le secteur du logiciel m\u00e9dical.<\/p>\n<p><span class=\"VIiyi\" lang=\"fr\"><span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"fr\" data-language-to-translate-into=\"en\" data-phrase-index=\"0\">L&rsquo;ancien actionnaire majoritaire, ARUBA Holding, continuera \u00e0 d\u00e9tenir une participation minoritaire dans la soci\u00e9t\u00e9, tandis que l&rsquo;ancien actionnaire minoritaire Med 360\u00b0 AG quittera le groupe d&rsquo;actionnaires dans le cadre de la transaction.<\/span><\/span><\/p>\n<h2>Notre r\u00f4le<\/h2>\n<p>Investec a conseill\u00e9 les actionnaires d&rsquo;i-SOLUTIONS Health tout au long du process de cession de l&rsquo;entreprise : strat\u00e9gie de l&rsquo;op\u00e9ration, pr\u00e9paration de la documentation marketing, approche et s\u00e9lection des acqu\u00e9reurs potentiels, coordination des due diligence, assistance \u00e0 la n\u00e9gociation etc.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contexte de l&rsquo;op\u00e9ration i-SOLUTIONS Health est une soci\u00e9t\u00e9 allemande sp\u00e9cialis\u00e9e dans les logiciels pour la sant\u00e9 \u00e0 destination des h\u00f4pitaux,&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","dt":[],"sector":[3768,3697],"dealtype":[3706],"clienttype":[3699],"class_list":["post-26156","deals","type-deals","status-publish","hentry","sector-healthcare-fr","sector-fr-sector-expertise-tmt","dealtype-cession-fr","clienttype-mid-market-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cession d&#039;i-Solutions Health \u00e0 Trill Impact | Investec Business Advisory<\/title>\n<meta name=\"description\" content=\"Investec a conseill\u00e9 i-SOLUTIONS Health \u00e0 l&#039;occasion de la cession de Trill Impact.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.investec.com\/advisory\/fr\/deals\/cession-di-solutions-health-a-trill-impact\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cession d&#039;i-Solutions Health \u00e0 Trill Impact | Investec Business Advisory\" \/>\n<meta property=\"og:description\" content=\"Investec a conseill\u00e9 i-SOLUTIONS Health \u00e0 l&#039;occasion de la cession de Trill Impact.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.investec.com\/advisory\/fr\/deals\/cession-di-solutions-health-a-trill-impact\/\" \/>\n<meta property=\"og:site_name\" content=\"Investec Business Advisory\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-21T13:31:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/cession-di-solutions-health-a-trill-impact\\\/\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/cession-di-solutions-health-a-trill-impact\\\/\",\"name\":\"Cession d'i-Solutions Health \u00e0 Trill Impact | Investec Business Advisory\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#website\"},\"datePublished\":\"2021-08-06T06:57:43+00:00\",\"dateModified\":\"2021-10-21T13:31:35+00:00\",\"description\":\"Investec a conseill\u00e9 i-SOLUTIONS Health \u00e0 l'occasion de la cession de Trill Impact.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/cession-di-solutions-health-a-trill-impact\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/cession-di-solutions-health-a-trill-impact\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/cession-di-solutions-health-a-trill-impact\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cession d&#8217;i-Solutions Health \u00e0 Trill Impact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/\",\"name\":\"Investec Business Advisory\",\"description\":\"Investec Business Advisory\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#organization\",\"name\":\"Capitalmind Investec\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Logo_Investec_cmjn_6.jpg\",\"contentUrl\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Logo_Investec_cmjn_6.jpg\",\"width\":1120,\"height\":1121,\"caption\":\"Capitalmind Investec\"},\"image\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/capitalmind---corporate-finance-advisory\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC4bVt7iNejh8tGT6Qfa9R4w\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cession d'i-Solutions Health \u00e0 Trill Impact | Investec Business Advisory","description":"Investec a conseill\u00e9 i-SOLUTIONS Health \u00e0 l'occasion de la cession de Trill Impact.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.investec.com\/advisory\/fr\/deals\/cession-di-solutions-health-a-trill-impact\/","og_locale":"fr_FR","og_type":"article","og_title":"Cession d'i-Solutions Health \u00e0 Trill Impact | Investec Business Advisory","og_description":"Investec a conseill\u00e9 i-SOLUTIONS Health \u00e0 l'occasion de la cession de Trill Impact.","og_url":"https:\/\/www.investec.com\/advisory\/fr\/deals\/cession-di-solutions-health-a-trill-impact\/","og_site_name":"Investec Business Advisory","article_modified_time":"2021-10-21T13:31:35+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.investec.com\/advisory\/fr\/deals\/cession-di-solutions-health-a-trill-impact\/","url":"https:\/\/www.investec.com\/advisory\/fr\/deals\/cession-di-solutions-health-a-trill-impact\/","name":"Cession d'i-Solutions Health \u00e0 Trill Impact | Investec Business Advisory","isPartOf":{"@id":"https:\/\/www.investec.com\/advisory\/fr\/#website"},"datePublished":"2021-08-06T06:57:43+00:00","dateModified":"2021-10-21T13:31:35+00:00","description":"Investec a conseill\u00e9 i-SOLUTIONS Health \u00e0 l'occasion de la cession de Trill Impact.","breadcrumb":{"@id":"https:\/\/www.investec.com\/advisory\/fr\/deals\/cession-di-solutions-health-a-trill-impact\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.investec.com\/advisory\/fr\/deals\/cession-di-solutions-health-a-trill-impact\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.investec.com\/advisory\/fr\/deals\/cession-di-solutions-health-a-trill-impact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.investec.com\/advisory\/fr\/"},{"@type":"ListItem","position":2,"name":"Cession d&#8217;i-Solutions Health \u00e0 Trill Impact"}]},{"@type":"WebSite","@id":"https:\/\/www.investec.com\/advisory\/fr\/#website","url":"https:\/\/www.investec.com\/advisory\/fr\/","name":"Investec Business Advisory","description":"Investec Business Advisory","publisher":{"@id":"https:\/\/www.investec.com\/advisory\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.investec.com\/advisory\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.investec.com\/advisory\/fr\/#organization","name":"Capitalmind Investec","url":"https:\/\/www.investec.com\/advisory\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.investec.com\/advisory\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.investec.com\/advisory\/wp-content\/uploads\/2020\/01\/Logo_Investec_cmjn_6.jpg","contentUrl":"https:\/\/www.investec.com\/advisory\/wp-content\/uploads\/2020\/01\/Logo_Investec_cmjn_6.jpg","width":1120,"height":1121,"caption":"Capitalmind Investec"},"image":{"@id":"https:\/\/www.investec.com\/advisory\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/capitalmind---corporate-finance-advisory","https:\/\/www.youtube.com\/channel\/UC4bVt7iNejh8tGT6Qfa9R4w"]}]}},"_links":{"self":[{"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/deals\/26156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/deals"}],"about":[{"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/types\/deals"}],"wp:attachment":[{"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/media?parent=26156"}],"wp:term":[{"taxonomy":"dt","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/dt?post=26156"},{"taxonomy":"sector","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/sector?post=26156"},{"taxonomy":"dealtype","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/dealtype?post=26156"},{"taxonomy":"clienttype","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/clienttype?post=26156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}