{"id":51014,"date":"2021-02-20T09:44:00","date_gmt":"2021-02-20T08:44:00","guid":{"rendered":"https:\/\/editing.capitalmind.com\/?post_type=deals&#038;p=51014"},"modified":"2025-05-05T17:33:45","modified_gmt":"2025-05-05T15:33:45","slug":"levee-de-fonds-par-sanjay-mariwala-pour-omniactive","status":"publish","type":"deals","link":"https:\/\/www.investec.com\/advisory\/fr\/deals\/levee-de-fonds-par-sanjay-mariwala-pour-omniactive\/","title":{"rendered":"Lev\u00e9e de fonds de 46 millions d&rsquo;USD par Sanjay Mariwala dans OmniActive"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Investec a conseill\u00e9 Sanjay Mariwala et OmniActive dans le cadre de leur lev\u00e9e de fonds de 46 millions de dollars aupr\u00e8s d&rsquo;Investec Private Credit et d&rsquo;Axis Capital.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A propos du deal<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Investec a \u00e9t\u00e9 le conseil financier exclusif de Sanjaya Mariwala et de sa famille, ainsi que d&rsquo;OmniActive Health Technologies ( \u00bb OmniActive \u00bb), dans le cadre de sa lev\u00e9e de fonds de 46 millions de dollars aupr\u00e8s d&rsquo;Investec Private Credit et d&rsquo;Axis Capital, afin de consolider la participation de Sanjaya Mariwala au sein d&rsquo;OmniActive.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Op\u00e9ration tr\u00e8s complexe r\u00e9alis\u00e9e en parall\u00e8le \u00e0 la prise de participation de TA dans OmniActive, une lev\u00e9e de fonds structur\u00e9e par le fondateur de sa soci\u00e9t\u00e9 holding pour financer son co-investissement avec TA dans OmniActive et la s\u00e9paration de l&rsquo;activit\u00e9 B2C d&rsquo;OmniActive.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A propos d&rsquo;OmniActive<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">OmniActive est un acteur de premier plan dans la fourniture d\u2019ingr\u00e9dients actifs naturels destin\u00e9s aux secteurs des compl\u00e9ments alimentaires, de l\u2019enrichissement nutritionnel et des aliments fonctionnels. OmniActive offre une gamme d\u2019ingr\u00e9dients de marque, cliniquement prouv\u00e9s et scientifiquement v\u00e9rifi\u00e9s qui permettent aux marques de nutrition du monde entier de fournir des suppl\u00e9ments qui r\u00e9pondent aux exigences du march\u00e9 dynamique de la sant\u00e9 et du bien-\u00eatre. Soutenue par des clients de premier plan tels que Bausch &amp; Lomb, GNC, Costco, etc. OmniActive b\u00e9n\u00e9ficie d\u2019une forte demande de sa client\u00e8le internationale et nationale.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Notre r\u00f4le<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Investec a jou\u00e9 un r\u00f4le cl\u00e9 pour combiner harmonieusement les droits et obligations du fonds de capital-investissement, du fonds de cr\u00e9dit et du fondateur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Investec a conseill\u00e9 Sanjay Mariwala et OmniActive dans le cadre de leur lev\u00e9e de fonds de 46 millions de dollars&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","dt":[17021,17022,17023],"sector":[3725,3768],"dealtype":[3718,3740],"clienttype":[3733],"class_list":["post-51014","deals","type-deals","status-publish","hentry","dt-fundraise-fr","dt-industrials-2-fr","dt-private-company-fr","sector-consumer-fr","sector-healthcare-fr","dealtype-debt-advisory-fr","dealtype-capital-dev-fr","clienttype-grands-groupes-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lev\u00e9e de fonds de 46 millions d&#039;USD par Sanjay Mariwala dans OmniActive | Investec Business Advisory<\/title>\n<meta name=\"description\" content=\"Investec a conseill\u00e9 Sanjay Mariwala et OmniActive dans le cadre de leur lev\u00e9e de fonds de 46 millions de dollars aupr\u00e8s d&#039;Investec Private Credit et d&#039;Axis Capital.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.investec.com\/advisory\/fr\/deals\/levee-de-fonds-par-sanjay-mariwala-pour-omniactive\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lev\u00e9e de fonds de 46 millions d&#039;USD par Sanjay Mariwala dans OmniActive | Investec Business Advisory\" \/>\n<meta property=\"og:description\" content=\"Investec a conseill\u00e9 Sanjay Mariwala et OmniActive dans le cadre de leur lev\u00e9e de fonds de 46 millions de dollars aupr\u00e8s d&#039;Investec Private Credit et d&#039;Axis Capital.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.investec.com\/advisory\/fr\/deals\/levee-de-fonds-par-sanjay-mariwala-pour-omniactive\/\" \/>\n<meta property=\"og:site_name\" content=\"Investec Business Advisory\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-05T15:33:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/levee-de-fonds-par-sanjay-mariwala-pour-omniactive\\\/\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/levee-de-fonds-par-sanjay-mariwala-pour-omniactive\\\/\",\"name\":\"Lev\u00e9e de fonds de 46 millions d'USD par Sanjay Mariwala dans OmniActive | Investec Business Advisory\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#website\"},\"datePublished\":\"2021-02-20T08:44:00+00:00\",\"dateModified\":\"2025-05-05T15:33:45+00:00\",\"description\":\"Investec a conseill\u00e9 Sanjay Mariwala et OmniActive dans le cadre de leur lev\u00e9e de fonds de 46 millions de dollars aupr\u00e8s d'Investec Private Credit et d'Axis Capital.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/levee-de-fonds-par-sanjay-mariwala-pour-omniactive\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/levee-de-fonds-par-sanjay-mariwala-pour-omniactive\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/levee-de-fonds-par-sanjay-mariwala-pour-omniactive\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lev\u00e9e de fonds de 46 millions d&#8217;USD par Sanjay Mariwala dans OmniActive\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/\",\"name\":\"Investec Business Advisory\",\"description\":\"Investec Business Advisory\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#organization\",\"name\":\"Capitalmind Investec\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Logo_Investec_cmjn_6.jpg\",\"contentUrl\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Logo_Investec_cmjn_6.jpg\",\"width\":1120,\"height\":1121,\"caption\":\"Capitalmind Investec\"},\"image\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/capitalmind---corporate-finance-advisory\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC4bVt7iNejh8tGT6Qfa9R4w\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lev\u00e9e de fonds de 46 millions d'USD par Sanjay Mariwala dans OmniActive | Investec Business Advisory","description":"Investec a conseill\u00e9 Sanjay Mariwala et OmniActive dans le cadre de leur lev\u00e9e de fonds de 46 millions de dollars aupr\u00e8s d'Investec Private Credit et d'Axis Capital.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.investec.com\/advisory\/fr\/deals\/levee-de-fonds-par-sanjay-mariwala-pour-omniactive\/","og_locale":"fr_FR","og_type":"article","og_title":"Lev\u00e9e de fonds de 46 millions d'USD par Sanjay Mariwala dans OmniActive | Investec Business Advisory","og_description":"Investec a conseill\u00e9 Sanjay Mariwala et OmniActive dans le cadre de leur lev\u00e9e de fonds de 46 millions de dollars aupr\u00e8s d'Investec Private Credit et d'Axis Capital.","og_url":"https:\/\/www.investec.com\/advisory\/fr\/deals\/levee-de-fonds-par-sanjay-mariwala-pour-omniactive\/","og_site_name":"Investec Business Advisory","article_modified_time":"2025-05-05T15:33:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.investec.com\/advisory\/fr\/deals\/levee-de-fonds-par-sanjay-mariwala-pour-omniactive\/","url":"https:\/\/www.investec.com\/advisory\/fr\/deals\/levee-de-fonds-par-sanjay-mariwala-pour-omniactive\/","name":"Lev\u00e9e de fonds de 46 millions d'USD par Sanjay Mariwala dans OmniActive | Investec Business Advisory","isPartOf":{"@id":"https:\/\/www.investec.com\/advisory\/fr\/#website"},"datePublished":"2021-02-20T08:44:00+00:00","dateModified":"2025-05-05T15:33:45+00:00","description":"Investec a conseill\u00e9 Sanjay Mariwala et OmniActive dans le cadre de leur lev\u00e9e de fonds de 46 millions de dollars aupr\u00e8s d'Investec Private Credit et d'Axis Capital.","breadcrumb":{"@id":"https:\/\/www.investec.com\/advisory\/fr\/deals\/levee-de-fonds-par-sanjay-mariwala-pour-omniactive\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.investec.com\/advisory\/fr\/deals\/levee-de-fonds-par-sanjay-mariwala-pour-omniactive\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.investec.com\/advisory\/fr\/deals\/levee-de-fonds-par-sanjay-mariwala-pour-omniactive\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.investec.com\/advisory\/fr\/"},{"@type":"ListItem","position":2,"name":"Lev\u00e9e de fonds de 46 millions d&#8217;USD par Sanjay Mariwala dans OmniActive"}]},{"@type":"WebSite","@id":"https:\/\/www.investec.com\/advisory\/fr\/#website","url":"https:\/\/www.investec.com\/advisory\/fr\/","name":"Investec Business Advisory","description":"Investec Business Advisory","publisher":{"@id":"https:\/\/www.investec.com\/advisory\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.investec.com\/advisory\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.investec.com\/advisory\/fr\/#organization","name":"Capitalmind Investec","url":"https:\/\/www.investec.com\/advisory\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.investec.com\/advisory\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.investec.com\/advisory\/wp-content\/uploads\/2020\/01\/Logo_Investec_cmjn_6.jpg","contentUrl":"https:\/\/www.investec.com\/advisory\/wp-content\/uploads\/2020\/01\/Logo_Investec_cmjn_6.jpg","width":1120,"height":1121,"caption":"Capitalmind Investec"},"image":{"@id":"https:\/\/www.investec.com\/advisory\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/capitalmind---corporate-finance-advisory","https:\/\/www.youtube.com\/channel\/UC4bVt7iNejh8tGT6Qfa9R4w"]}]}},"_links":{"self":[{"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/deals\/51014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/deals"}],"about":[{"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/types\/deals"}],"wp:attachment":[{"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/media?parent=51014"}],"wp:term":[{"taxonomy":"dt","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/dt?post=51014"},{"taxonomy":"sector","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/sector?post=51014"},{"taxonomy":"dealtype","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/dealtype?post=51014"},{"taxonomy":"clienttype","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/clienttype?post=51014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}