{"id":52282,"date":"2025-04-03T14:27:23","date_gmt":"2025-04-03T12:27:23","guid":{"rendered":"https:\/\/editing.capitalmind.com\/?post_type=deals&#038;p=52282"},"modified":"2025-04-03T14:53:55","modified_gmt":"2025-04-03T12:53:55","slug":"acquisition-techni-prefa-pa-rector-lesage","status":"publish","type":"deals","link":"https:\/\/www.investec.com\/advisory\/fr\/deals\/acquisition-techni-prefa-pa-rector-lesage\/","title":{"rendered":"Acquisition de Techni Prefa par Rector Lesage"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Investec a conseill\u00e9 Rector Lesage dans l\u2019acquisition de Techni Prefa<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A propos du deal<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Fond\u00e9e en 1985 et implant\u00e9e \u00e0 Thouars (79), Techni Prefa r\u00e9alise un chiffre d&rsquo;affaires de pr\u00e8s de 55 M\u20ac dans la fabrication d&rsquo;\u00e9l\u00e9ments en b\u00e9ton arm\u00e9 sur-mesure (murs, poteaux, poutres, longrines). Positionn\u00e9 sur un march\u00e9 r\u00e9silient et en croissance, l&rsquo;entreprise intervient directement aupr\u00e8s des grands groupes du b\u00e2timent, de travaux publics et de g\u00e9nie civil, en France, dans les domaines de la logistique, de l&rsquo;industrie et du tertiaire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entreprise innovante et pr\u00e9curseur, Techni Prefa b\u00e9n\u00e9ficie d\u2019une usine moderne et puissante, capable de r\u00e9pondre \u00e0 de fortes demandes tout en maintenant des standards de qualit\u00e9 \u00e9lev\u00e9s. Port\u00e9e par ses 130 employ\u00e9s, Techni Prefa s\u2019impose comme un acteur de r\u00e9f\u00e9rence sur les segments majeurs de la charpente:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Leader des poteaux en France, avec environ 12 % de parts de march\u00e9.<\/li>\n\n\n\n<li>Pr\u00e9curseur sur les charpentes mixtes bois\/b\u00e9ton, une solution en pleine expansion.<\/li>\n\n\n\n<li>Expertise des murs coupe-feu, avec une capacit\u00e9 de production de pr\u00e8s de 300 000 m\u00b2 par an.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Comptant parmi les leaders du march\u00e9 fran\u00e7ais de la fabrication d&rsquo;\u00e9l\u00e9ments en b\u00e9ton pour le march\u00e9 de la construction, le Groupe Rector adresse 3 principaux segments de client\u00e8le (maison individuelle et group\u00e9es, logements collectifs et tertiaires, b\u00e2timents industriel et commerciaux) et offre une large gamme de produits (planchers, ossatures, murs, poutrelles, pr\u00e9dalles, etc..). L&rsquo;acquisition de Techni Prefa par Rector Lesage, permet au groupe de se positionner sur des offres compl\u00e9mentaires s&rsquo;int\u00e9grant parfaitement au dispositif industriel existant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pr\u00e9sent sur un march\u00e9 comp\u00e9titif, Rector Lesage entend poursuivre la strat\u00e9gie de d\u00e9veloppement amorc\u00e9e par Techni Prefa tout en impl\u00e9mentant les synergies commerciales et industrielles identifi\u00e9es pour acc\u00e9l\u00e9rer le d\u00e9veloppement et optimiser les performances op\u00e9rationnelles notamment sur le march\u00e9 de la charpente mixte et de la charpente multi-niveaux.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le rapprochement de Techni Prefa au sein de Rector Lesage permet ainsi de constituer le leader fran\u00e7ais de l\u2019ossature charpente en France.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Notre r\u00f4le<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Investec a accompagn\u00e9 Rector Lesage tout au long du processus d\u2019acquisition : <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conseils en mati\u00e8re de valorisation ; <\/li>\n\n\n\n<li>Assistance dans la r\u00e9daction et la n\u00e9gociation des offres indicatives et fermes ; <\/li>\n\n\n\n<li>Gestion du processus de <em>due diligence<\/em> ;<\/li>\n\n\n\n<li>Assistance dans les n\u00e9gociations finales de la documentation juridique.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Investec a conseill\u00e9 Rector Lesage dans l\u2019acquisition de Techni Prefa A propos du deal Fond\u00e9e en 1985 et implant\u00e9e \u00e0&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","dt":[],"sector":[3711],"dealtype":[3698],"clienttype":[3699],"class_list":["post-52282","deals","type-deals","status-publish","hentry","sector-industrie-fr","dealtype-acquisition-fr","clienttype-mid-market-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acquisition de Techni Prefa par Rector Lesage | Investec Business Advisory<\/title>\n<meta name=\"description\" content=\"Investec Business Advisory Acquisition de Techni Prefa par Rector Lesage Investec a conseill\u00e9 Rector Lesage dans l\u2019acquisition de Techni Prefa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.investec.com\/advisory\/fr\/deals\/acquisition-techni-prefa-pa-rector-lesage\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acquisition de Techni Prefa par Rector Lesage | Investec Business Advisory\" \/>\n<meta property=\"og:description\" content=\"Investec Business Advisory Acquisition de Techni Prefa par Rector Lesage Investec a conseill\u00e9 Rector Lesage dans l\u2019acquisition de Techni Prefa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.investec.com\/advisory\/fr\/deals\/acquisition-techni-prefa-pa-rector-lesage\/\" \/>\n<meta property=\"og:site_name\" content=\"Investec Business Advisory\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-03T12:53:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/acquisition-techni-prefa-pa-rector-lesage\\\/\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/acquisition-techni-prefa-pa-rector-lesage\\\/\",\"name\":\"Acquisition de Techni Prefa par Rector Lesage | Investec Business Advisory\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#website\"},\"datePublished\":\"2025-04-03T12:27:23+00:00\",\"dateModified\":\"2025-04-03T12:53:55+00:00\",\"description\":\"Investec Business Advisory Acquisition de Techni Prefa par Rector Lesage Investec a conseill\u00e9 Rector Lesage dans l\u2019acquisition de Techni Prefa\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/acquisition-techni-prefa-pa-rector-lesage\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/acquisition-techni-prefa-pa-rector-lesage\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/acquisition-techni-prefa-pa-rector-lesage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acquisition de Techni Prefa par Rector Lesage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/\",\"name\":\"Investec Business Advisory\",\"description\":\"Investec Business Advisory\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#organization\",\"name\":\"Capitalmind Investec\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Logo_Investec_cmjn_6.jpg\",\"contentUrl\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Logo_Investec_cmjn_6.jpg\",\"width\":1120,\"height\":1121,\"caption\":\"Capitalmind Investec\"},\"image\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/capitalmind---corporate-finance-advisory\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC4bVt7iNejh8tGT6Qfa9R4w\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acquisition de Techni Prefa par Rector Lesage | Investec Business Advisory","description":"Investec Business Advisory Acquisition de Techni Prefa par Rector Lesage Investec a conseill\u00e9 Rector Lesage dans l\u2019acquisition de Techni Prefa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.investec.com\/advisory\/fr\/deals\/acquisition-techni-prefa-pa-rector-lesage\/","og_locale":"fr_FR","og_type":"article","og_title":"Acquisition de Techni Prefa par Rector Lesage | Investec Business Advisory","og_description":"Investec Business Advisory Acquisition de Techni Prefa par Rector Lesage Investec a conseill\u00e9 Rector Lesage dans l\u2019acquisition de Techni Prefa","og_url":"https:\/\/www.investec.com\/advisory\/fr\/deals\/acquisition-techni-prefa-pa-rector-lesage\/","og_site_name":"Investec Business Advisory","article_modified_time":"2025-04-03T12:53:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.investec.com\/advisory\/fr\/deals\/acquisition-techni-prefa-pa-rector-lesage\/","url":"https:\/\/www.investec.com\/advisory\/fr\/deals\/acquisition-techni-prefa-pa-rector-lesage\/","name":"Acquisition de Techni Prefa par Rector Lesage | Investec Business Advisory","isPartOf":{"@id":"https:\/\/www.investec.com\/advisory\/fr\/#website"},"datePublished":"2025-04-03T12:27:23+00:00","dateModified":"2025-04-03T12:53:55+00:00","description":"Investec Business Advisory Acquisition de Techni Prefa par Rector Lesage Investec a conseill\u00e9 Rector Lesage dans l\u2019acquisition de Techni Prefa","breadcrumb":{"@id":"https:\/\/www.investec.com\/advisory\/fr\/deals\/acquisition-techni-prefa-pa-rector-lesage\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.investec.com\/advisory\/fr\/deals\/acquisition-techni-prefa-pa-rector-lesage\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.investec.com\/advisory\/fr\/deals\/acquisition-techni-prefa-pa-rector-lesage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.investec.com\/advisory\/fr\/"},{"@type":"ListItem","position":2,"name":"Acquisition de Techni Prefa par Rector Lesage"}]},{"@type":"WebSite","@id":"https:\/\/www.investec.com\/advisory\/fr\/#website","url":"https:\/\/www.investec.com\/advisory\/fr\/","name":"Investec Business Advisory","description":"Investec Business Advisory","publisher":{"@id":"https:\/\/www.investec.com\/advisory\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.investec.com\/advisory\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.investec.com\/advisory\/fr\/#organization","name":"Capitalmind Investec","url":"https:\/\/www.investec.com\/advisory\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.investec.com\/advisory\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.investec.com\/advisory\/wp-content\/uploads\/2020\/01\/Logo_Investec_cmjn_6.jpg","contentUrl":"https:\/\/www.investec.com\/advisory\/wp-content\/uploads\/2020\/01\/Logo_Investec_cmjn_6.jpg","width":1120,"height":1121,"caption":"Capitalmind Investec"},"image":{"@id":"https:\/\/www.investec.com\/advisory\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/capitalmind---corporate-finance-advisory","https:\/\/www.youtube.com\/channel\/UC4bVt7iNejh8tGT6Qfa9R4w"]}]}},"_links":{"self":[{"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/deals\/52282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/deals"}],"about":[{"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/types\/deals"}],"wp:attachment":[{"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/media?parent=52282"}],"wp:term":[{"taxonomy":"dt","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/dt?post=52282"},{"taxonomy":"sector","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/sector?post=52282"},{"taxonomy":"dealtype","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/dealtype?post=52282"},{"taxonomy":"clienttype","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/clienttype?post=52282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}