{"id":53397,"date":"2025-06-09T15:23:37","date_gmt":"2025-06-09T13:23:37","guid":{"rendered":"https:\/\/editing.capitalmind.com\/?post_type=deals&#038;p=53397"},"modified":"2025-06-10T10:11:41","modified_gmt":"2025-06-10T08:11:41","slug":"acquisition-d-electrical-components-international-par-rosebank-industries","status":"publish","type":"deals","link":"https:\/\/www.investec.com\/advisory\/fr\/deals\/acquisition-d-electrical-components-international-par-rosebank-industries\/","title":{"rendered":"Acquisition d&rsquo;Electrical Components International par Rosebank Industries et lev\u00e9e de fonds de 1,14 milliard de livres sterling"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Investec conseille Rosebank Industries dans le cadre de l&rsquo;acquisition d&rsquo;Electrical Components International pour 1,9 milliard de dollars et de sa lev\u00e9e de fonds de 1,14 milliard de livres sterling.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A propos du deal<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Notre \u00e9quipe UK Corporate Broking &amp; PLC Advisory est ravie d&rsquo;avoir agi en tant que coordinateur global conjoint, conseil financier, conseil d\u00e9sign\u00e9 et courtier conjoint pour Rosebank Industries plc, soci\u00e9t\u00e9 d&rsquo;investissement britannique, dans le cadre de l&rsquo;acquisition aupr\u00e8s de \u00a0la soci\u00e9t\u00e9 de capital-investissement Cerberus Capital Management de la soci\u00e9t\u00e9 am\u00e9ricaine Electrical Components International Inc (ECI) pour 1,9 milliard de dollars et dans sa lev\u00e9e de fonds de 1,14 milliard de livres sterling (1.55 milliards de dollars) pour financer l&rsquo;acquisition.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;acquisition est financ\u00e9e par une lev\u00e9e de fonds enti\u00e8rement garantie \u00e0 3 livres sterling par action et de nouvelles facilit\u00e9s de cr\u00e9dit, et devrait co\u00fbter moins de 1,9 milliard de dollars.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette transaction marque une \u00e9tape importante pour Rosebank Industries, puisqu&rsquo;il s&rsquo;agit de sa premi\u00e8re acquisition depuis son introduction en bourse en juillet 2024, et d\u00e9montre le soutien continu d&rsquo;Investec \u00e0 une \u00e9quipe de direction avec laquelle elle travaille depuis plus de 22 ans.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il s&rsquo;agit du plus important placement primaire sur les march\u00e9s boursiers britanniques depuis 2020, du plus important placement jamais r\u00e9alis\u00e9 sur l&rsquo;AIM et de la quatri\u00e8me op\u00e9ration ECM r\u00e9alis\u00e9e par notre \u00e9quipe britannique sp\u00e9cialis\u00e9e dans le secteur des biens d&rsquo;\u00e9quipement au cours des 12 derniers mois.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 propos de Rosebank Industries plc<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rosebank a \u00e9t\u00e9 cr\u00e9\u00e9e en 2024 dans le but d&rsquo;acqu\u00e9rir des entreprises dont les administrateurs estiment que les performances peuvent \u00eatre am\u00e9lior\u00e9es afin de cr\u00e9er de la valeur pour les actionnaires. La strat\u00e9gie de Rosebank consiste \u00e0 acqu\u00e9rir des entreprises industrielles ou manufacturi\u00e8res de qualit\u00e9, dot\u00e9es de fondamentaux solides et dont les performances peuvent \u00eatre am\u00e9lior\u00e9es. En investissant dans les entreprises acquises, en modifiant l&rsquo;orientation de la direction et en apportant des am\u00e9liorations op\u00e9rationnelles, Rosebank cherche \u00e0 accro\u00eetre et \u00e0 r\u00e9aliser la valeur de ces entreprises, g\u00e9n\u00e9ralement sur un horizon d&rsquo;investissement de trois \u00e0 cinq ans, et \u00e0 reverser le produit de la vente aux actionnaires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 propos d&rsquo;Electrical Components International<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fond\u00e9e en 1953, ECI est l&rsquo;un des principaux fournisseurs mondiaux de syst\u00e8mes de distribution \u00e9lectrique, de bo\u00eetiers de commande et d&rsquo;autres composants techniques destin\u00e9s \u00e0 une gamme diversifi\u00e9e, allant des appareils \u00e9lectrom\u00e9nagers aux \u00e9quipements industriels intelligents. Avec environ 20 000 employ\u00e9s et 39 sites de production dans le monde, ECI est le partenaire de confiance de plus de 450 clients. ECI fournit des solutions intelligentes, connect\u00e9es et \u00e9lectrifi\u00e9es qui permettent aux technologies les plus avanc\u00e9es de relever les d\u00e9fis les plus complexes.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00ab Le soutien d&rsquo;Investec a \u00e9t\u00e9 inestimable tout au long du processus. Son expertise et sa compr\u00e9hension des march\u00e9s financiers ont jou\u00e9 un r\u00f4le essentiel dans la facilitation de cette acquisition. Nous sommes impatients de poursuivre notre partenariat dans le cadre de la mise en \u0153uvre de notre mod\u00e8le \u00ab acheter, am\u00e9liorer, vendre \u00bb et de cr\u00e9er une valeur significative pour nos actionnaires. Nous n&rsquo;aurions pas pu conclure cette transaction sans Investec. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 <strong>Simon Peckham, directeur g\u00e9n\u00e9ral de Rosebank<\/strong><\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00ab Investec entretient des relations tr\u00e8s solides avec l&rsquo;\u00e9quipe de Rosebank, et nous sommes fiers de les accompagner dans cette premi\u00e8re acquisition et lev\u00e9e de fonds majeure. Apr\u00e8s avoir travaill\u00e9 avec Rosebank pendant plus de 22 ans, nous sommes ravis de participer \u00e0 cette nouvelle aventure et nous nous r\u00e9jouissons d&rsquo;aider Rosebank \u00e0 devenir un acteur industriel majeur au Royaume-Uni. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 <strong>Carlton Nelson, <strong>Head of Corporate Broking &amp; PLC Advisory<\/strong> chez Investec<\/strong><\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Investec conseille Rosebank Industries dans le cadre de l&rsquo;acquisition d&rsquo;Electrical Components International pour 1,9 milliard de dollars et de sa&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","dt":[],"sector":[3711,16931],"dealtype":[3698,3718,3740],"clienttype":[3720,3733],"class_list":["post-53397","deals","type-deals","status-publish","hentry","sector-industrie-fr","sector-services-financiers-fr","dealtype-acquisition-fr","dealtype-debt-advisory-fr","dealtype-capital-dev-fr","clienttype-pe-fr","clienttype-grands-groupes-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acquisition d&#039;Electrical Components International par Rosebank Industries et lev\u00e9e de fonds de 1,14 milliard de livres sterling | Investec Business Advisory<\/title>\n<meta name=\"description\" content=\"Acquisition d&#039;Electrical Components International par Rosebank Industries et lev\u00e9e de fonds de 1,14 milliard de livres sterling\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.investec.com\/advisory\/fr\/deals\/acquisition-d-electrical-components-international-par-rosebank-industries\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acquisition d&#039;Electrical Components International par Rosebank Industries et lev\u00e9e de fonds de 1,14 milliard de livres sterling | Investec Business Advisory\" \/>\n<meta property=\"og:description\" content=\"Acquisition d&#039;Electrical Components International par Rosebank Industries et lev\u00e9e de fonds de 1,14 milliard de livres sterling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.investec.com\/advisory\/fr\/deals\/acquisition-d-electrical-components-international-par-rosebank-industries\/\" \/>\n<meta property=\"og:site_name\" content=\"Investec Business Advisory\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-10T08:11:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/acquisition-d-electrical-components-international-par-rosebank-industries\\\/\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/acquisition-d-electrical-components-international-par-rosebank-industries\\\/\",\"name\":\"Acquisition d'Electrical Components International par Rosebank Industries et lev\u00e9e de fonds de 1,14 milliard de livres sterling | Investec Business Advisory\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#website\"},\"datePublished\":\"2025-06-09T13:23:37+00:00\",\"dateModified\":\"2025-06-10T08:11:41+00:00\",\"description\":\"Acquisition d'Electrical Components International par Rosebank Industries et lev\u00e9e de fonds de 1,14 milliard de livres sterling\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/acquisition-d-electrical-components-international-par-rosebank-industries\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/acquisition-d-electrical-components-international-par-rosebank-industries\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/deals\\\/acquisition-d-electrical-components-international-par-rosebank-industries\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acquisition d&#8217;Electrical Components International par Rosebank Industries et lev\u00e9e de fonds de 1,14 milliard de livres sterling\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/\",\"name\":\"Investec Business Advisory\",\"description\":\"Investec Business Advisory\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#organization\",\"name\":\"Capitalmind Investec\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Logo_Investec_cmjn_6.jpg\",\"contentUrl\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Logo_Investec_cmjn_6.jpg\",\"width\":1120,\"height\":1121,\"caption\":\"Capitalmind Investec\"},\"image\":{\"@id\":\"https:\\\/\\\/www.investec.com\\\/advisory\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/capitalmind---corporate-finance-advisory\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC4bVt7iNejh8tGT6Qfa9R4w\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acquisition d'Electrical Components International par Rosebank Industries et lev\u00e9e de fonds de 1,14 milliard de livres sterling | Investec Business Advisory","description":"Acquisition d'Electrical Components International par Rosebank Industries et lev\u00e9e de fonds de 1,14 milliard de livres sterling","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.investec.com\/advisory\/fr\/deals\/acquisition-d-electrical-components-international-par-rosebank-industries\/","og_locale":"fr_FR","og_type":"article","og_title":"Acquisition d'Electrical Components International par Rosebank Industries et lev\u00e9e de fonds de 1,14 milliard de livres sterling | Investec Business Advisory","og_description":"Acquisition d'Electrical Components International par Rosebank Industries et lev\u00e9e de fonds de 1,14 milliard de livres sterling","og_url":"https:\/\/www.investec.com\/advisory\/fr\/deals\/acquisition-d-electrical-components-international-par-rosebank-industries\/","og_site_name":"Investec Business Advisory","article_modified_time":"2025-06-10T08:11:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.investec.com\/advisory\/fr\/deals\/acquisition-d-electrical-components-international-par-rosebank-industries\/","url":"https:\/\/www.investec.com\/advisory\/fr\/deals\/acquisition-d-electrical-components-international-par-rosebank-industries\/","name":"Acquisition d'Electrical Components International par Rosebank Industries et lev\u00e9e de fonds de 1,14 milliard de livres sterling | Investec Business Advisory","isPartOf":{"@id":"https:\/\/www.investec.com\/advisory\/fr\/#website"},"datePublished":"2025-06-09T13:23:37+00:00","dateModified":"2025-06-10T08:11:41+00:00","description":"Acquisition d'Electrical Components International par Rosebank Industries et lev\u00e9e de fonds de 1,14 milliard de livres sterling","breadcrumb":{"@id":"https:\/\/www.investec.com\/advisory\/fr\/deals\/acquisition-d-electrical-components-international-par-rosebank-industries\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.investec.com\/advisory\/fr\/deals\/acquisition-d-electrical-components-international-par-rosebank-industries\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.investec.com\/advisory\/fr\/deals\/acquisition-d-electrical-components-international-par-rosebank-industries\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.investec.com\/advisory\/fr\/"},{"@type":"ListItem","position":2,"name":"Acquisition d&#8217;Electrical Components International par Rosebank Industries et lev\u00e9e de fonds de 1,14 milliard de livres sterling"}]},{"@type":"WebSite","@id":"https:\/\/www.investec.com\/advisory\/fr\/#website","url":"https:\/\/www.investec.com\/advisory\/fr\/","name":"Investec Business Advisory","description":"Investec Business Advisory","publisher":{"@id":"https:\/\/www.investec.com\/advisory\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.investec.com\/advisory\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.investec.com\/advisory\/fr\/#organization","name":"Capitalmind Investec","url":"https:\/\/www.investec.com\/advisory\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.investec.com\/advisory\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.investec.com\/advisory\/wp-content\/uploads\/2020\/01\/Logo_Investec_cmjn_6.jpg","contentUrl":"https:\/\/www.investec.com\/advisory\/wp-content\/uploads\/2020\/01\/Logo_Investec_cmjn_6.jpg","width":1120,"height":1121,"caption":"Capitalmind Investec"},"image":{"@id":"https:\/\/www.investec.com\/advisory\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/capitalmind---corporate-finance-advisory","https:\/\/www.youtube.com\/channel\/UC4bVt7iNejh8tGT6Qfa9R4w"]}]}},"_links":{"self":[{"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/deals\/53397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/deals"}],"about":[{"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/types\/deals"}],"wp:attachment":[{"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/media?parent=53397"}],"wp:term":[{"taxonomy":"dt","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/dt?post=53397"},{"taxonomy":"sector","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/sector?post=53397"},{"taxonomy":"dealtype","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/dealtype?post=53397"},{"taxonomy":"clienttype","embeddable":true,"href":"https:\/\/www.investec.com\/advisory\/fr\/wp-json\/wp\/v2\/clienttype?post=53397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}